{"id":1869,"date":"2024-06-19T15:23:41","date_gmt":"2024-06-19T20:23:41","guid":{"rendered":"https:\/\/perimeter.ca\/sites-dexpedition-et-de-fret\/"},"modified":"2024-10-07T09:02:17","modified_gmt":"2024-10-07T14:02:17","slug":"sites-dexpedition-et-de-fret","status":"publish","type":"page","link":"https:\/\/perimeter.ca\/fr\/sites-dexpedition-et-de-fret\/","title":{"rendered":"Localisation des sites"},"content":{"rendered":"\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Perimeter Cargo dispose d&rsquo;un vaste r\u00e9seau \u00e0 travers le Manitoba et le nord-ouest de l&rsquo;Ontario, reliant plus de 33 sites, dont beaucoup sont \u00e9loign\u00e9s.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nos principaux bureaux de fret sont situ\u00e9s \u00e0 Winnipeg, Thompson, Sioux Lookout et Thunder Bay.\nNous offrons des services quotidiens d&rsquo;exp\u00e9dition de marchandises \u00e0 destination et en provenance de n&rsquo;importe laquelle de nos destinations r\u00e9guli\u00e8res au Manitoba et dans le nord-ouest de l&rsquo;Ontario. <\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_2385-768x1024.jpg\" alt=\"\" class=\"wp-image-3351\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_2385-768x1024.jpg 768w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_2385-225x300.jpg 225w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_2385-1152x1536.jpg 1152w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_2385-scaled.jpg 1536w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"844\" height=\"1024\" src=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/20240308_101249-scaled-e1725911467793-844x1024.jpg\" alt=\"\" class=\"wp-image-3343\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/20240308_101249-scaled-e1725911467793-844x1024.jpg 844w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/20240308_101249-scaled-e1725911467793-247x300.jpg 247w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/20240308_101249-scaled-e1725911467793-768x932.jpg 768w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/20240308_101249-scaled-e1725911467793.jpg 1153w\" sizes=\"auto, (max-width: 844px) 100vw, 844px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-large is-style-rounded\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-1024x768.jpeg\" alt=\"\" class=\"wp-image-3347\" style=\"aspect-ratio:1;object-fit:cover\" srcset=\"https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-1024x768.jpeg 1024w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-300x225.jpeg 300w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-768x576.jpeg 768w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-1536x1152.jpeg 1536w, https:\/\/perimeter.ca\/wp-content\/uploads\/2024\/09\/IMG_6859-scaled.jpeg 2048w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Lieux d&rsquo;exp\u00e9dition<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Pour obtenir une liste compl\u00e8te des adresses des a\u00e9roports et des bureaux, des informations de contact et des heures d&rsquo;ouverture, consultez la page <a href=\"https:\/\/perimeter.ca\/fr\/contactez-nous\/\" data-type=\"page\" data-id=\"966\">Contactez-nous<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Manitoba<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Brochet, Cross Lake, God&rsquo;s Lake Narrows, God&rsquo;s River, Island Lake (Garden Hill), Lac Brochet, Norway House, Oxford House, Red Sucker, Shamattawa, South Indian Lake, St. Theresa Point (Wasagamack), Tadoule Lake, Thompson, York Landing, Winnipeg.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Ontario<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Deer Lake, North Bay, North Spirit Lake, Pikangikum, Red Lake, Sachigo Lake, Sandy Lake, Sault Ste. Marie, Sioux Lookout, Sudbury, Thunder Bay.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-orange-500-color has-alpha-channel-opacity has-orange-500-background-color has-background\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Prise en charge et d\u00e9pose  <\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Lorsque vous d\u00e9posez un colis en vue de son exp\u00e9dition, vous devez fournir une pi\u00e8ce d&rsquo;identit\u00e9 et inspecter les articles exp\u00e9di\u00e9s pour confirmer leur contenu. Consultez la rubrique <a href=\"https:\/\/perimeter.ca\/fr\/preparer-votre-envoi\/\">Pr\u00e9parer votre envoi<\/a> pour plus d&rsquo;informations.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Les clients ne sont pas autoris\u00e9s \u00e0 retirer des pi\u00e8ces partielles d&rsquo;un envoi, sauf si la lettre de transport a\u00e9rien est annul\u00e9e et que le client r\u00e9cup\u00e8re toutes les pi\u00e8ces originales dans leur int\u00e9gralit\u00e9.<\/p>\n\n\n\n<div style=\"height:55px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Perimeter Cargo dispose d&rsquo;un vaste r\u00e9seau \u00e0 travers le Manitoba et le nord-ouest de l&rsquo;Ontario, reliant plus de 33 sites, dont beaucoup sont \u00e9loign\u00e9s. Nos principaux bureaux de fret sont situ\u00e9s \u00e0 Winnipeg, Thompson, Sioux Lookout et Thunder Bay. Nous offrons des services quotidiens d&rsquo;exp\u00e9dition de marchandises \u00e0 destination et en provenance de n&rsquo;importe laquelle &hellip;<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"template-narrow.blade.php","meta":{"_acf_changed":true,"footnotes":""},"class_list":["post-1869","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/pages\/1869","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/comments?post=1869"}],"version-history":[{"count":0,"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/pages\/1869\/revisions"}],"wp:attachment":[{"href":"https:\/\/perimeter.ca\/fr\/wp-json\/wp\/v2\/media?parent=1869"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}